

{"id":199,"date":"2017-07-03T17:35:24","date_gmt":"2017-07-03T15:35:24","guid":{"rendered":"https:\/\/www.soparco.com\/?page_id=199\/"},"modified":"2018-03-07T16:14:32","modified_gmt":"2018-03-07T15:14:32","slug":"contacto","status":"publish","type":"page","link":"https:\/\/www.soparco.com\/es\/contacto\/","title":{"rendered":"Contacto"},"content":{"rendered":"<p>SOPARCO tiene 4 filales europeas y una presencia permanente en casi 25 paises. Nuestro servicio comercial y nuestros delegados comerciales est\u00e1n a vuestra escucha para contestar a vuestras preguntas. No dude en ponerse en contacto con ellos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SOPARCO tiene 4 filales europeas y una presencia permanente en casi 25 paises. Nuestro servicio comercial y nuestros delegados comerciales est\u00e1n a vuestra escucha para contestar a vuestras preguntas. No dude en ponerse en contacto con ellos.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-contact.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-199","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contacto - Soparco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.soparco.com\/es\/contacto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contacto - Soparco\" \/>\n<meta property=\"og:description\" content=\"SOPARCO tiene 4 filales europeas y una presencia permanente en casi 25 paises. Nuestro servicio comercial y nuestros delegados comerciales est\u00e1n a vuestra escucha para contestar a vuestras preguntas. No dude en ponerse en contacto con ellos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.soparco.com\/es\/contacto\/\" \/>\n<meta property=\"og:site_name\" content=\"Soparco\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-07T15:14:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.soparco.com\/es\/contacto\/\",\"url\":\"https:\/\/www.soparco.com\/es\/contacto\/\",\"name\":\"Contacto - Soparco\",\"isPartOf\":{\"@id\":\"https:\/\/www.soparco.com\/#website\"},\"datePublished\":\"2017-07-03T15:35:24+00:00\",\"dateModified\":\"2018-03-07T15:14:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.soparco.com\/es\/contacto\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.soparco.com\/es\/contacto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.soparco.com\/es\/contacto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.soparco.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contacto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.soparco.com\/#website\",\"url\":\"https:\/\/www.soparco.com\/\",\"name\":\"Soparco\",\"description\":\"Leader fran\u00e7ais du pot en plastique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.soparco.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contacto - Soparco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.soparco.com\/es\/contacto\/","og_locale":"es_ES","og_type":"article","og_title":"Contacto - Soparco","og_description":"SOPARCO tiene 4 filales europeas y una presencia permanente en casi 25 paises. Nuestro servicio comercial y nuestros delegados comerciales est\u00e1n a vuestra escucha para contestar a vuestras preguntas. No dude en ponerse en contacto con ellos.","og_url":"https:\/\/www.soparco.com\/es\/contacto\/","og_site_name":"Soparco","article_modified_time":"2018-03-07T15:14:32+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.soparco.com\/es\/contacto\/","url":"https:\/\/www.soparco.com\/es\/contacto\/","name":"Contacto - Soparco","isPartOf":{"@id":"https:\/\/www.soparco.com\/#website"},"datePublished":"2017-07-03T15:35:24+00:00","dateModified":"2018-03-07T15:14:32+00:00","breadcrumb":{"@id":"https:\/\/www.soparco.com\/es\/contacto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.soparco.com\/es\/contacto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.soparco.com\/es\/contacto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.soparco.com\/"},{"@type":"ListItem","position":2,"name":"Contacto"}]},{"@type":"WebSite","@id":"https:\/\/www.soparco.com\/#website","url":"https:\/\/www.soparco.com\/","name":"Soparco","description":"Leader fran\u00e7ais du pot en plastique","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.soparco.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.soparco.com\/es\/wp-json\/wp\/v2\/pages\/199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soparco.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.soparco.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.soparco.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soparco.com\/es\/wp-json\/wp\/v2\/comments?post=199"}],"version-history":[{"count":4,"href":"https:\/\/www.soparco.com\/es\/wp-json\/wp\/v2\/pages\/199\/revisions"}],"predecessor-version":[{"id":586,"href":"https:\/\/www.soparco.com\/es\/wp-json\/wp\/v2\/pages\/199\/revisions\/586"}],"wp:attachment":[{"href":"https:\/\/www.soparco.com\/es\/wp-json\/wp\/v2\/media?parent=199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}